{"id":15781,"date":"2024-10-16T15:08:27","date_gmt":"2024-10-16T13:08:27","guid":{"rendered":"https:\/\/toypek.eu\/product\/toypek-sanitaire-unit-copy\/"},"modified":"2025-10-07T15:55:00","modified_gmt":"2025-10-07T13:55:00","slug":"sanitaire-unit","status":"publish","type":"product","link":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/","title":{"rendered":"Luxe mobiele sanitaire unit"},"content":{"rendered":"\n<p>Onze mobiele sanitaire units zijn verkrijgbaar in vier kleuren: blauw, groen, rood en oranje. Deze units zijn &lsquo;&rsquo;hufterproof&rsquo;&rsquo; ontworpen en makkelijk te vervoeren. Ze zijn speciaal ontwikkeld voor verhuurders met langdurige projecten, waar riool- en wateraansluitingen aanwezig zijn. Water- en rioolvoorzieningen zijn vaak de eerste werkzaamheden op een bouwplaats. Voor langdurige projecten kunt u uw klant een luxere sanitaire unit aanbieden en zelf besparen op servicetijd en schoonmaakkosten.<\/p>\n<p>Onze mobiele sanitaire units hebben de volgende voordelen:<\/p>\n<ul>\n<li>Gemakkelijk te tillen met een heftruck en ook makkelijk te verplaatsen met de hand.<\/li>\n<li>Snel te installeren met &eacute;&eacute;n watertoevoerpunt (Gardena-koppeling aan de achterzijde) en &eacute;&eacute;n afvoerpunt via een 110mm rioolbuis.<\/li>\n<li>Lichtgewicht, met een gewicht van ongeveer 90 kg.<\/li>\n<li>Gemaakt van hufterproof materialen voor een lange levensduur en eenvoudig schoon te maken.<\/li>\n<\/ul>\n<p>U kunt de mobiele sanitaire unit kopen voor verhuur aan bouwplaatsen, loodsen, havens, campings en andere locaties met vaste aansluitingen. Het is ook mogelijk om de unit ongemonteerd af te nemen, maar we raden aan om deze gemonteerd te kopen.<\/p>\n<p>Heeft u vragen over onze mobiele sanitaire units of speciale wensen? Ons team staat voor u klaar!<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Bent u op zoek naar een sanitaire unit die perfect aansluit bij uw wensen? Stel uw mobiele sanitair eenvoudig zelf samen met de knop hieronder. Kies de kleur, voeg extra opties toe en geef het gewenste aantal aan. Wij zorgen voor een op maat gemaakte offerte die volledig aansluit bij uw behoeften. Het is zelfs mogelijk om uw sanitaire unit geheel in eigen kleur te laten fabriceren.<\/p>\n<p>&nbsp;<\/p>\n<p>Liever direct contact? Bel vrijblijvend naar <a href=\"tel:06-11751657\">06-11751657<\/a>.<\/p>\n","protected":false},"featured_media":12312,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[20,22],"product_tag":[],"class_list":["post-15781","product","type-product","status-publish","has-post-thumbnail","product_cat-mobiele-toiletten","product_cat-sanitaire-unit","first","instock","shipping-taxable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Product - Mobiele sanitaire toilet unit kopen? Wc unit kopen<\/title>\n<meta name=\"description\" content=\"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luxe mobiele sanitaire unit\" \/>\n<meta property=\"og:description\" content=\"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/\" \/>\n<meta property=\"og:site_name\" content=\"Toypek\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T13:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.toypek.eu\/images\/tp-img-01-48.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/\",\"url\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/\",\"name\":\"Product - Mobiele sanitaire toilet unit kopen? Wc unit kopen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.toypek.eu\\\/images\\\/tp-img-01-48.png\",\"datePublished\":\"2024-10-16T13:08:27+00:00\",\"dateModified\":\"2025-10-07T13:55:00+00:00\",\"description\":\"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.toypek.eu\\\/images\\\/tp-img-01-48.png\",\"contentUrl\":\"https:\\\/\\\/cdn.toypek.eu\\\/images\\\/tp-img-01-48.png\",\"width\":1000,\"height\":1000,\"caption\":\"Toypek sanitaire unit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/product\\\/sanitaire-unit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/assortiment\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luxe mobiele sanitaire unit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/\",\"name\":\"Toypek\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toypek.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Product - Mobiele sanitaire toilet unit kopen? Wc unit kopen","description":"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"Luxe mobiele sanitaire unit","og_description":"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!","og_url":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/","og_site_name":"Toypek","article_modified_time":"2025-10-07T13:55:00+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/cdn.toypek.eu\/images\/tp-img-01-48.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/","url":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/","name":"Product - Mobiele sanitaire toilet unit kopen? Wc unit kopen","isPartOf":{"@id":"https:\/\/toypek.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/#primaryimage"},"image":{"@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.toypek.eu\/images\/tp-img-01-48.png","datePublished":"2024-10-16T13:08:27+00:00","dateModified":"2025-10-07T13:55:00+00:00","description":"Onze mobiele sanitaire toiletunits zijn \u2018\u2019hufterproef\u2019\u2019 ontworpen en gemakkelijk te transporteren. Bekijk de units hier!","breadcrumb":{"@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/#primaryimage","url":"https:\/\/cdn.toypek.eu\/images\/tp-img-01-48.png","contentUrl":"https:\/\/cdn.toypek.eu\/images\/tp-img-01-48.png","width":1000,"height":1000,"caption":"Toypek sanitaire unit"},{"@type":"BreadcrumbList","@id":"https:\/\/toypek.eu\/nl\/product\/sanitaire-unit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toypek.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/toypek.eu\/nl\/assortiment\/"},{"@type":"ListItem","position":3,"name":"Luxe mobiele sanitaire unit"}]},{"@type":"WebSite","@id":"https:\/\/toypek.eu\/nl\/#website","url":"https:\/\/toypek.eu\/nl\/","name":"Toypek","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toypek.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/product\/15781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/comments?post=15781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/media\/12312"}],"wp:attachment":[{"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/media?parent=15781"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/product_brand?post=15781"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/product_cat?post=15781"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/toypek.eu\/nl\/wp-json\/wp\/v2\/product_tag?post=15781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}